{"id":137,"date":"2022-02-12T10:27:48","date_gmt":"2022-02-12T10:27:48","guid":{"rendered":"https:\/\/ionogenic.com\/de\/home"},"modified":"2022-03-29T18:00:39","modified_gmt":"2022-03-29T18:00:39","slug":"home","status":"publish","type":"page","link":"https:\/\/ionogenic.com\/de\/","title":{"rendered":"Home"},"content":{"rendered":"\t<div class=\"cnvs-block-section cnvs-block-section-1571120080472 cnvs-block-section-layout-full cnvs-block-section-fullwidth\" >\n\t\t<div class=\"cnvs-block-section-outer\" style=\"\">\n\t\t\t<div class=\"cnvs-block-section-inner\">\n\t\t\t\t\r\n\r\n\n<div class=\"cnvs-block-section-content cnvs-block-section-content-1571120082557\" >\n\t<div class=\"cnvs-block-section-content-inner\">\n\t\t\r\n\r\n\n\t<div class=\"cnvs-block-posts cnvs-block-featured-posts-1571120096691 cnvs-block-posts-layout-tiles-8\">\n\n\t\t<div class=\"cs-block-tiles tiles-8\">\n\n\t\t\t<div class=\"tiles-outer\">\n\n\t\t\t\t\n\t\t\t\t\t<article class=\" layout-type-primary layout-size-large layout-typography-large post-378 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t\t\t\t\t\t<div class=\"post-outer overlay\">\n\t\t\t\t\t\t\t<div class=\"overlay-media parallax\" >\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b15-560x400.jpg\" class=\"jarallax-img wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"overlay-outer post-inner\">\n\t\t\t\t\t\t\t\t<div class=\"overlay-inner\">\n\n\t\t\t\t\t\t\t\t\t<ul class=\"post-meta\"><li class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/li><\/ul>\n\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/oclean-x-pro-elite-mit-w10-munddusche-im-test\/\">Oclean X Pro Elite mit W10 Munddusche im Test<\/a>\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"view-post-button\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t<a class=\"wp-block-button__link  button-effect\" href=\"https:\/\/ionogenic.com\/de\/oclean-x-pro-elite-mit-w10-munddusche-im-test\/\" target=\"\">\n\t\t\t<span>View Post<\/span>\n\t\t\t<span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span>\n\t\t<\/a>\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/oclean-x-pro-elite-mit-w10-munddusche-im-test\/\" class=\"overlay-link\"><\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\n\t\t\t\t\n\t\t\t\t\t<article class=\" layout-type-secondary layout-size-medium layout-typography-small post-382 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t\t\t\t\t\t<div class=\"post-outer overlay\">\n\t\t\t\t\t\t\t<div class=\"overlay-media parallax\" >\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b13-320x320.jpg\" class=\"jarallax-img wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b13-320x320.jpg 320w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b13-80x80.jpg 80w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b13-400x400.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b13-120x120.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b13-90x90.jpg 90w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"overlay-outer post-inner\">\n\t\t\t\t\t\t\t\t<div class=\"overlay-inner\">\n\n\t\t\t\t\t\t\t\t\t<ul class=\"post-meta\"><li class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/li><\/ul>\n\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/anleitung-zum-besten-benutzerdefinierten-beschreibbaren-sound-button\/\">Anleitung zum besten benutzerdefinierten beschreibbaren Sound-Button<\/a>\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/anleitung-zum-besten-benutzerdefinierten-beschreibbaren-sound-button\/\" class=\"overlay-link\"><\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\n\t\t\t\t\n\t\t\t\t\t<article class=\" layout-type-secondary layout-size-medium layout-typography-small post-370 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t\t\t\t\t\t<div class=\"post-outer overlay\">\n\t\t\t\t\t\t\t<div class=\"overlay-media parallax\" >\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-320x320.jpg\" class=\"jarallax-img wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-320x320.jpg 320w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-80x80.jpg 80w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-400x400.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-120x120.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-90x90.jpg 90w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"overlay-outer post-inner\">\n\t\t\t\t\t\t\t\t<div class=\"overlay-inner\">\n\n\t\t\t\t\t\t\t\t\t<ul class=\"post-meta\"><li class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/li><\/ul>\n\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\">Leitfaden f\u00fcr die besten drahtlosen SDI-Sender und -Empf\u00e4nger<\/a>\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\" class=\"overlay-link\"><\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\n\t\t\t\t\n\t\t\t\t\t<article class=\" layout-type-secondary layout-size-medium layout-typography-small post-402 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t\t\t\t\t\t<div class=\"post-outer overlay\">\n\t\t\t\t\t\t\t<div class=\"overlay-media parallax\" >\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b20-320x320.jpg\" class=\"jarallax-img wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b20-320x320.jpg 320w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b20-80x80.jpg 80w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b20-400x400.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b20-120x120.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b20-90x90.jpg 90w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"overlay-outer post-inner\">\n\t\t\t\t\t\t\t\t<div class=\"overlay-inner\">\n\n\t\t\t\t\t\t\t\t\t<ul class=\"post-meta\"><li class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/li><\/ul>\n\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/vergleich-bob-und-brad-q2-mini-vs-c2-massagepistole\/\">Vergleich Bob und Brad Q2 Mini vs. C2 Massagepistole<\/a>\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/vergleich-bob-und-brad-q2-mini-vs-c2-massagepistole\/\" class=\"overlay-link\"><\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\n\t\t\t\t\n\t\t\t\t\t<article class=\" layout-type-secondary layout-size-medium layout-typography-small post-390 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t\t\t\t\t\t<div class=\"post-outer overlay\">\n\t\t\t\t\t\t\t<div class=\"overlay-media parallax\" >\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"320\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b9-320x320.jpg\" class=\"jarallax-img wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b9-320x320.jpg 320w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b9-80x80.jpg 80w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b9-400x400.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b9-120x120.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b9-90x90.jpg 90w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"overlay-outer post-inner\">\n\t\t\t\t\t\t\t\t<div class=\"overlay-inner\">\n\n\t\t\t\t\t\t\t\t\t<ul class=\"post-meta\"><li class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/li><\/ul>\n\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/beste-wasserdurchflussmesser-fur-gartenschlauche\/\">Beste Wasserdurchflussmesser f\u00fcr Gartenschl\u00e4uche<\/a>\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/beste-wasserdurchflussmesser-fur-gartenschlauche\/\" class=\"overlay-link\"><\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\n\t<\/div>\n\n\t\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\r\n\r\n\t<div class=\"cnvs-block-section cnvs-block-section-1571318436466 cnvs-block-section-layout-with-sidebar cnvs-block-section-sidebar-sticky-top cnvs-block-section-sidebar-position-right\" >\n\t\t<div class=\"cnvs-block-section-outer\" style=\"\">\n\t\t\t<div class=\"cnvs-block-section-inner\">\n\t\t\t\t\r\n\r\n\n<div class=\"cnvs-block-section-content cnvs-block-section-content-1571120149786\" >\n\t<div class=\"cnvs-block-section-content-inner\">\n\t\t\r\n\r\n\n<h5 id=\"elektroniktechnologie-gadgets-rezensionen\" class=\"cnvs-block-section-heading cnvs-block-section-heading-1572265089722 is-style-cnvs-block-section-heading-default halignleft\" >\n\t<span class=\"cnvs-section-title\">\n\t\t<span>ELEKTRONIKTECHNOLOGIE &#038; GADGETS REZENSIONEN<\/span>\n\t<\/span>\n<\/h5>\n\r\n\r\n\n<div class=\"cs-block-archive-posts cnvs-block-featured-posts-1571120154893\" data-layout=\"grid\">\n\n\t<div class=\"post-archive\" data-archive-data=\"\">\n\t\t<div class=\"archive-main archive-grid columns-2\">\n<article class=\"post-grid post-392 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t<div class=\"post-outer\">\n\n\t\t\n\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t<div class=\"post-thumbnail\">\n\t\t\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-560x400.jpg\" class=\"attachment-csco-560-landscape size-csco-560-landscape wp-post-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-more\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-zu-den-besten-luftfahrt-headsets-fur-piloten\/\" class=\"button-link\">\n\t\t\t\t\t\t\t\t<span>View Post<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-zu-den-besten-luftfahrt-headsets-fur-piloten\/\"><\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t<div class=\"post-inner\">\n\n\t\t\t\n\t\t\t<header class=\"entry-header\">\n\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t<h2 class=\"entry-title\"><a href=\"https:\/\/ionogenic.com\/de\/leitfaden-zu-den-besten-luftfahrt-headsets-fur-piloten\/\">Leitfaden zu den besten Luftfahrt-Headsets f\u00fcr Piloten<\/a><\/h2>\n\n\t\t\t\t\t\t\t<\/header>\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"post-excerpt\">\n\t\t\t\t\t\t\t\tHeadsets sind eines der ersten Ausr\u00fcstungsgegenst\u00e4nde, die jeder Flugsch\u00fcler kaufen wird.\u00a0Flugsch\u00fcler, die auf das Mieten oder Leihen angewiesen sind, finden ihre Ausr\u00fcstung m\u00f6glicherweise&hellip;\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n<\/article>\n\n<article class=\"post-grid post-388 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t<div class=\"post-outer\">\n\n\t\t\n\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t<div class=\"post-thumbnail\">\n\t\t\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-560x400.jpg\" class=\"attachment-csco-560-landscape size-csco-560-landscape wp-post-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-more\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/die-besten-zangenmessgerate-fur-tragbare-ac-dc-tests\/\" class=\"button-link\">\n\t\t\t\t\t\t\t\t<span>View Post<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/die-besten-zangenmessgerate-fur-tragbare-ac-dc-tests\/\"><\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t<div class=\"post-inner\">\n\n\t\t\t\n\t\t\t<header class=\"entry-header\">\n\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t<h2 class=\"entry-title\"><a href=\"https:\/\/ionogenic.com\/de\/die-besten-zangenmessgerate-fur-tragbare-ac-dc-tests\/\">Die besten Zangenmessger\u00e4te f\u00fcr tragbare AC\/DC-Tests<\/a><\/h2>\n\n\t\t\t\t\t\t\t<\/header>\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"post-excerpt\">\n\t\t\t\t\t\t\t\tDie meisten von uns haben ein paar Werkzeuge im Haus.\u00a0Zumindest haben wir ein paar Schraubendreher, Schraubenschl\u00fcssel und andere grundlegende Handwerkzeuge.\u00a0Aber in einer Welt, die zunehmend&hellip;\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n<\/article>\n\n<article class=\"post-grid post-370 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t<div class=\"post-outer\">\n\n\t\t\n\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t<div class=\"post-thumbnail\">\n\t\t\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-560x400.jpg\" class=\"attachment-csco-560-landscape size-csco-560-landscape wp-post-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-more\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\" class=\"button-link\">\n\t\t\t\t\t\t\t\t<span>View Post<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\"><\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t<div class=\"post-inner\">\n\n\t\t\t\n\t\t\t<header class=\"entry-header\">\n\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t<h2 class=\"entry-title\"><a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\">Leitfaden f\u00fcr die besten drahtlosen SDI-Sender und -Empf\u00e4nger<\/a><\/h2>\n\n\t\t\t\t\t\t\t<\/header>\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"post-excerpt\">\n\t\t\t\t\t\t\t\tWenn Sie ein Videofilmer, Fotograf oder Kameramann sind, k\u00f6nnen Sie nicht immer station\u00e4r bleiben. Sicher, ein einfaches Stativ reicht f\u00fcr einige Aufnahmen v\u00f6llig aus. Aber in anderen F\u00e4llen&hellip;\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n<\/article>\n\n<article class=\"post-grid post-372 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t<div class=\"post-outer\">\n\n\t\t\n\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t<div class=\"post-thumbnail\">\n\t\t\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b18-560x400.jpg\" class=\"attachment-csco-560-landscape size-csco-560-landscape wp-post-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-more\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/idondrdo-fitness-smartwatch-und-gesundheitsmonitor-im-test\/\" class=\"button-link\">\n\t\t\t\t\t\t\t\t<span>View Post<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/idondrdo-fitness-smartwatch-und-gesundheitsmonitor-im-test\/\"><\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t<div class=\"post-inner\">\n\n\t\t\t\n\t\t\t<header class=\"entry-header\">\n\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t<h2 class=\"entry-title\"><a href=\"https:\/\/ionogenic.com\/de\/idondrdo-fitness-smartwatch-und-gesundheitsmonitor-im-test\/\">IDONDRDO Fitness Smartwatch und Gesundheitsmonitor im Test<\/a><\/h2>\n\n\t\t\t\t\t\t\t<\/header>\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"post-excerpt\">\n\t\t\t\t\t\t\t\tWenn Sie eine Zeitmaschine in die 1990er Jahre zur\u00fcckversetzen w\u00fcrden, w\u00fcrden Sie feststellen, dass jeder eine Uhr trug. Es geh\u00f6rte einfach dazu, ein verantwortungsbewusster Erwachsener zu&hellip;\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n<\/article>\n<\/div>\t<\/div>\n\n<\/div>\n\t\t<\/div>\n<\/div>\n\r\n\r\n\n<div class=\"cnvs-block-section-sidebar cnvs-block-section-sidebar-1571120149832\" >\n\t<div class=\"cnvs-block-section-sidebar-inner\">\n\t\t\r\n\r\n\r\n<p style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/ionogenic.com\/wp-content\/uploads\/2022\/02\/ad.png\" alt=\"ad\" \/> \u00a0<\/p>\r\n\r\n\r\n\n<h5 id=\"beliebt\" class=\"cnvs-block-section-heading cnvs-block-section-heading-1572265093311 is-style-cnvs-block-section-heading-default haligncenter\" >\n\t<span class=\"cnvs-section-title\">\n\t\t<span>BELIEBT<\/span>\n\t<\/span>\n<\/h5>\n\r\n\r\n\t<div class=\"cnvs-block-posts-sidebar cnvs-block-featured-posts-1571121240081 cnvs-block-posts-sidebar-numbered\">\n\t\t<div class=\"cnvs-block-posts-sidebar-inner\">\n\t\t\t<ul class=\"cnvs-posts-list\">\n\t\t\t\t\t\t\t\t\t<li class=\"cnvs-post-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"layout-size-small post-392 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\t\t\t\t\t\t\t\t<div class=\"post-outer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-zu-den-besten-luftfahrt-headsets-fur-piloten\/\" class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-90x90.jpg\" class=\"attachment-csco-90-square size-csco-90-square wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-90x90.jpg 90w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-80x80.jpg 80w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-400x400.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-120x120.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-320x320.jpg 320w\" sizes=\"auto, (max-width: 90px) 100vw, 90px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>1<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-zu-den-besten-luftfahrt-headsets-fur-piloten\/\">Leitfaden zu den besten Luftfahrt-Headsets f\u00fcr Piloten<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"cnvs-post-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"layout-size-small post-388 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\t\t\t\t\t\t\t\t<div class=\"post-outer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/die-besten-zangenmessgerate-fur-tragbare-ac-dc-tests\/\" class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-90x90.jpg\" class=\"attachment-csco-90-square size-csco-90-square wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-90x90.jpg 90w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-80x80.jpg 80w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-400x400.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-120x120.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-320x320.jpg 320w\" sizes=\"auto, (max-width: 90px) 100vw, 90px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>2<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/die-besten-zangenmessgerate-fur-tragbare-ac-dc-tests\/\">Die besten Zangenmessger\u00e4te f\u00fcr tragbare AC\/DC-Tests<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"cnvs-post-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"layout-size-small post-370 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\t\t\t\t\t\t\t\t<div class=\"post-outer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\" class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-90x90.jpg\" class=\"attachment-csco-90-square size-csco-90-square wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-90x90.jpg 90w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-80x80.jpg 80w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-400x400.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-120x120.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-320x320.jpg 320w\" sizes=\"auto, (max-width: 90px) 100vw, 90px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>3<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\">Leitfaden f\u00fcr die besten drahtlosen SDI-Sender und -Empf\u00e4nger<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"cnvs-post-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"layout-size-small post-372 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\t\t\t\t\t\t\t\t<div class=\"post-outer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/idondrdo-fitness-smartwatch-und-gesundheitsmonitor-im-test\/\" class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b18-90x90.jpg\" class=\"attachment-csco-90-square size-csco-90-square wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b18-90x90.jpg 90w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b18-80x80.jpg 80w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b18-400x400.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b18-120x120.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b18-320x320.jpg 320w\" sizes=\"auto, (max-width: 90px) 100vw, 90px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>4<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/idondrdo-fitness-smartwatch-und-gesundheitsmonitor-im-test\/\">IDONDRDO Fitness Smartwatch und Gesundheitsmonitor im Test<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"cnvs-post-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"layout-size-small post-374 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\t\t\t\t\t\t\t\t<div class=\"post-outer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/hohem-isteady-q-gimbal-stabilisator-fur-smartphones\/\" class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b17-90x90.jpg\" class=\"attachment-csco-90-square size-csco-90-square wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b17-90x90.jpg 90w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b17-80x80.jpg 80w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b17-400x400.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b17-120x120.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b17-320x320.jpg 320w\" sizes=\"auto, (max-width: 90px) 100vw, 90px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-number\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>5<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/hohem-isteady-q-gimbal-stabilisator-fur-smartphones\/\">Hohem iSteady Q \u2013 Gimbal-Stabilisator f\u00fcr Smartphones<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\r\n<p style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/ionogenic.com\/wp-content\/uploads\/2022\/02\/ad.png\" alt=\"ad\" \/> \u00a0<\/p>\r\n\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\r\n\r\n\t<div class=\"cnvs-block-section cnvs-block-section-1571121172253 cnvs-block-section-layout-full cnvs-block-section-fullwidth\" >\n\t\t<div class=\"cnvs-block-section-outer\" style=\"\">\n\t\t\t<div class=\"cnvs-block-section-inner\">\n\t\t\t\t\r\n\r\n\n<div class=\"cnvs-block-section-content cnvs-block-section-content-1571121173918\" >\n\t<div class=\"cnvs-block-section-content-inner\">\n\t\t\r\n\r\n\n<h5 id=\"das-neueste\" class=\"cnvs-block-section-heading cnvs-block-section-heading-1572265298048 is-style-cnvs-block-section-heading-default haligncenter\" >\n\t<span class=\"cnvs-section-title\">\n\t\t<span>DAS NEUESTE<\/span>\n\t<\/span>\n<\/h5>\n\r\n\r\n\n<div class=\"cs-block-archive-posts cnvs-block-featured-posts-1571121176770\" data-layout=\"masonry\">\n\n\t<div class=\"post-archive\" data-archive-data=\"\">\n\t\t<div class=\"archive-main archive-masonry archive-compact columns-3\"><div class=\"archive-col archive-col-1\"><\/div><div class=\"archive-col archive-col-2\"><\/div><div class=\"archive-col archive-col-3\"><\/div>\n<article class=\"post-masonry post-392 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t<div class=\"post-outer\">\n\n\t\t\n\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t<div class=\"post-thumbnail\">\n\t\t\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"240\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-320x240.jpg\" class=\"attachment-csco-320-landscape size-csco-320-landscape wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-320x240.jpg 320w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-300x225.jpg 300w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-400x300.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-120x90.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b8-90x68.jpg 90w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-more\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-zu-den-besten-luftfahrt-headsets-fur-piloten\/\" class=\"button-link\">\n\t\t\t\t\t\t\t\t<span>View Post<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-zu-den-besten-luftfahrt-headsets-fur-piloten\/\"><\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t<div class=\"post-inner\">\n\n\t\t\t\n\t\t\t<header class=\"entry-header\">\n\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t<h2 class=\"entry-title\"><a href=\"https:\/\/ionogenic.com\/de\/leitfaden-zu-den-besten-luftfahrt-headsets-fur-piloten\/\">Leitfaden zu den besten Luftfahrt-Headsets f\u00fcr Piloten<\/a><\/h2>\n\n\t\t\t\t\t\t\t<\/header>\n\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n<\/article>\n\n<article class=\"post-masonry post-388 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t<div class=\"post-outer\">\n\n\t\t\n\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t<div class=\"post-thumbnail\">\n\t\t\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"240\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-320x240.jpg\" class=\"attachment-csco-320-landscape size-csco-320-landscape wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-320x240.jpg 320w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-300x225.jpg 300w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-400x300.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-120x90.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b10-90x68.jpg 90w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-more\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/die-besten-zangenmessgerate-fur-tragbare-ac-dc-tests\/\" class=\"button-link\">\n\t\t\t\t\t\t\t\t<span>View Post<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/die-besten-zangenmessgerate-fur-tragbare-ac-dc-tests\/\"><\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t<div class=\"post-inner\">\n\n\t\t\t\n\t\t\t<header class=\"entry-header\">\n\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t<h2 class=\"entry-title\"><a href=\"https:\/\/ionogenic.com\/de\/die-besten-zangenmessgerate-fur-tragbare-ac-dc-tests\/\">Die besten Zangenmessger\u00e4te f\u00fcr tragbare AC\/DC-Tests<\/a><\/h2>\n\n\t\t\t\t\t\t\t<\/header>\n\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n<\/article>\n\n<article class=\"post-masonry post-370 post type-post status-publish format-standard has-post-thumbnail category-news\">\n\n\t<div class=\"post-outer\">\n\n\t\t\n\t\t\t\t\t<div class=\"post-inner\">\n\t\t\t\t<div class=\"post-thumbnail\">\n\t\t\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"240\" src=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-320x240.jpg\" class=\"attachment-csco-320-landscape size-csco-320-landscape wp-post-image\" alt=\"\" srcset=\"https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-320x240.jpg 320w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-300x225.jpg 300w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-400x300.jpg 400w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-120x90.jpg 120w, https:\/\/ionogenic.com\/de\/wp-content\/uploads\/2022\/03\/b19-90x68.jpg 90w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-more\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\" class=\"button-link\">\n\t\t\t\t\t\t\t\t<span>View Post<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\"><\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t<div class=\"post-inner\">\n\n\t\t\t\n\t\t\t<header class=\"entry-header\">\n\t\t\t\t<div class=\"meta-category\"><ul class=\"post-categories\">\n\t<li><a href=\"https:\/\/ionogenic.com\/de\/category\/news\/\" rel=\"category tag\">Nachrichten<\/a><\/li><\/ul><\/div>\n\t\t\t\t<h2 class=\"entry-title\"><a href=\"https:\/\/ionogenic.com\/de\/leitfaden-fur-die-besten-drahtlosen-sdi-sender-und-empfanger\/\">Leitfaden f\u00fcr die besten drahtlosen SDI-Sender und -Empf\u00e4nger<\/a><\/h2>\n\n\t\t\t\t\t\t\t<\/header>\n\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n<\/article>\n<\/div>\t<\/div>\n\n<\/div>\n\t\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t","protected":false},"excerpt":{"rendered":"\u00a0 \u00a0","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-canvas-fullwidth.php","meta":{"footnotes":""},"class_list":["post-137","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/ionogenic.com\/de\/wp-json\/wp\/v2\/pages\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ionogenic.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ionogenic.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ionogenic.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ionogenic.com\/de\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":1,"href":"https:\/\/ionogenic.com\/de\/wp-json\/wp\/v2\/pages\/137\/revisions"}],"predecessor-version":[{"id":363,"href":"https:\/\/ionogenic.com\/de\/wp-json\/wp\/v2\/pages\/137\/revisions\/363"}],"wp:attachment":[{"href":"https:\/\/ionogenic.com\/de\/wp-json\/wp\/v2\/media?parent=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}